{"id":166,"date":"2019-05-29T08:21:13","date_gmt":"2019-05-29T08:21:13","guid":{"rendered":"http:\/\/kunstimaltenweingut.de\/contacts\/"},"modified":"2024-04-10T16:52:07","modified_gmt":"2024-04-10T14:52:07","slug":"kontakt","status":"publish","type":"page","link":"https:\/\/kunstimaltenweingut.de\/en\/kontakt\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"166\" class=\"elementor elementor-166\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70a9338 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"70a9338\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46379a5 sc-tablet_inner_width_none sc-tablet_content_align_inherit sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"46379a5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:218,&quot;url&quot;:&quot;https:\\\/\\\/kunstimaltenweingut.de\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Gemu\\u0308nden-Museum-17-03-21-080.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58420f2 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"58420f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f250344 scheme_dark sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"f250344\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-015c9e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"015c9e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a9d6a0d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"a9d6a0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50b7b38 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"50b7b38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_328680961\"\n\t\tclass=\"sc_title sc_title_default\"><h3 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"><span class=\"sc_item_title_text\">Museum Info<\/span><\/h3><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d98fbf8 sc_height_small animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d98fbf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-10d3ea9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10d3ea9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e075972 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"e075972\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3587983 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"3587983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_423422389\"\n\t\tclass=\"sc_title sc_title_default\"><h5 class=\"sc_item_title sc_title_title sc_item_title_style_default sc_item_title_tag\"><span class=\"sc_item_title_text\">Kontakt<\/span><\/h5><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10295a8 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"10295a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f855442 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f855442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fda0677 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"fda0677\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-640a20b animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"640a20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Telefon<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfb0ac0 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"dfb0ac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fax<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed34a94 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"ed34a94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a703b93 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"a703b93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">+49 (0)6130 94 93 282<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5fb4f6 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"f5fb4f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">+49 (0)6130 94 93 283<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-313a286 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"313a286\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6a50432 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"6a50432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0dfbc2a animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"0dfbc2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adresse<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e64f513 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"e64f513\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c8528 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"45c8528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tObentrautstrasse 3a,\n55218 Ingelheim &#8211;\nGro\u00dfwinternheim\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e343c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e343c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b3411e7 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"b3411e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f7ee77 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"3f7ee77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tE-Mail\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a0643 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"b6a0643\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Website<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4281274 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"4281274\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5809f1f animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"5809f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><span class=\"s1\"><a href=\"mailto:info@kunstimaltenweingut.de\">info@kunstimaltenweingut.de<\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20a27ce animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"20a27ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">kunstimaltenweingut.de<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d6b3e8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d6b3e8c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9549c37 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"9549c37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52ff48e animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"52ff48e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ba6cb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ba6cb3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7eaa835 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"7eaa835\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f1d55d animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2f1d55d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e1348ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1348ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-28a9e59 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"28a9e59\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1895e1f sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"1895e1f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06201a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06201a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-01cbc09 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"01cbc09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c8ec7c9 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"c8ec7c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09abed8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"09abed8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-82ec207 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"82ec207\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-745a87f animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"745a87f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-187d35d animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"187d35d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sie planen einen Besuch im Museum Obentraut3?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b0ebb1 elementor-widget__width-initial animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"3b0ebb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vereinbaren Sie eine F\u00fchrung, Gruppen von 10 \u2013 20 Personen bieten wir folgende Termine:<\/p><p>Mi\/Do\/Fr 10.30 Uhr oder 14.30 Uhr, Sa 14.30 Uhr, So 10.30 Uhr<\/p><p>(Mo und Di geschlossen)<\/p><p>Gr\u00f6\u00dfere Gruppen k\u00f6nnen geteilt und m\u00f6glichst zeitgleich gef\u00fchrt werden, f\u00fcr kleinere Gruppen versuchen wir gemeinsame Termine zu finden.<\/p><p><strong><b>Terminanfragen richten Sie bitte mindestens eine Woche zuvor an info@kunstimaltenweingut.de, die Bearbeitung erfolgt Mo \u2013 Do jeweils zwischen 8.00 und 15.00 Uhr, in dieser Zeit sind auch telefonische Anfragen m\u00f6glich.<\/b><\/strong><\/p><p><strong><b>Belegte Tage sind im Kalender gekennzeichnet, \u00c4nderungen vorbehalten.<\/b><\/strong><\/p><p>Im September findet au\u00dferdem ein Tag der offenen T\u00fcr statt.<\/p><div>\u00a0<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4999dce animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"4999dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_1905788569\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Kalender<\/span><\/h4><div id=\"sc_button_1304541425\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/de\/events\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">hier<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db8616a animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"db8616a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-744b2cc animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"744b2cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91ca2f8 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"91ca2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Museum Obentraut3<\/p><p class=\"p1\">Obentrautstra\u00dfe 3a | 55218 Ingelheim-Gro\u00dfwinternheim<\/p><p class=\"p1\">Tel.: 06130 94 93 282<\/p><p class=\"p1\">Fax: 06130 94 93 283<\/p><p class=\"p1\">Mail: <a href=\"mailto:info@kunstimaltenweingut.de\"><span class=\"s1\">info@kunstimaltenweingut.de<\/span><\/a><\/p><p class=\"p1\">Web: www.kunstimaltenweingut.de<\/p><p>Stiftung Gem\u00fcnden &amp; Freunde | Sparkasse Rhein-Nahe |<br \/>Iban: DE74 5605 0180 0017 1303 45<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10f0b54 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"10f0b54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c2dbe3 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_socials\" data-id=\"6c2dbe3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_socials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  id=\"trx_sc_socials_731038737\" \n\t\tclass=\"sc_socials sc_socials_default sc_align_none\"><div class=\"socials_wrap\"><\/div><!-- \/.socials_wrap --><\/div><!-- \/.sc_socials -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d38c76d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"d38c76d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e49be6b animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e49be6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52f330c animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"52f330c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8312d66 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_contact_form_7\" data-id=\"8312d66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f144-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"144\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/166#wpcf7-f144-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"144\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f144-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label> Ihr Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Ihre E-Mail-Adresse<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Betreff<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Ihre Nachricht (optional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n\n<!-- Unsichtbares Honeypot-Feld -->\n<p><span id=\"wpcf7-6a048154e454e-wrapper\" class=\"wpcf7-form-control-wrap coolbox42-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a048154e454e-field\" class=\"hp-message\">Bitte lasse dieses Feld leer.<\/label><input id=\"wpcf7-6a048154e454e-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"coolbox42\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c9270a animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2c9270a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc4ba8d sc_height_huge animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"bc4ba8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6762ed elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"b6762ed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71abf72 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"71abf72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7684ac sc_height_huge animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a7684ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4254ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4254ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5eb62eb sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"5eb62eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3bad2f8 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"3bad2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_998247461\"\n\t\tclass=\"sc_title sc_title_decoration extra_vision\"><h3 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">H\u00e4ufig gestellte Fragen<\/span><\/h3><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d60ba16 sc_height_medium animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d60ba16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-81bee8d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"81bee8d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-62872c6 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"62872c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-236bc88 animation_type_block sc_fly_static elementor-widget elementor-widget-toggle\" data-id=\"236bc88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-3711\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-3711\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie kann ich spenden?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-3711\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-3711\"><p class=\"p1\">Wir freuen uns, dass Sie der Kunststiftung eine Spende geben m\u00f6chten. Alle Details zu der \u00dcberweisung und Ihrer Spendenquittung erhalten Sie von der Museumsleitung. Diese erreichen Sie telefonisch unter 06130 9493282<\/p><p class=\"p1\">Stiftung Gem\u00fcnden &amp; Freunde | Sparkasse Rhein-Nahe |<br \/>Iban: DE74 5605 0180 0017 1303 45<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3ebc372 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"3ebc372\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c03840 animation_type_block sc_fly_static elementor-widget elementor-widget-toggle\" data-id=\"5c03840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9641\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9641\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Werden Gruppenf\u00fchrungen angeboten?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9641\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9641\"><p>\u00a0<\/p><p>Nach Absprache sind individuelle Gruppenf\u00fchrungen m\u00f6glich, wir bieten folgende Zeiten zur Auswahl:<\/p><p>Mi\/Do\/Fr 10.30 Uhr oder 14.30 Uhr, Sa 14.30 Uhr, So 10.30 Uhr<\/p><p>(Mo und Di geschlossen)<\/p><p><strong><b>Terminanfragen richten Sie bitte mindestens eine Woche zuvor an info@kunstimaltenweingut.de, die Bearbeitung erfolgt Mo \u2013 Do jeweils zwischen 8.00 und 15.00 Uhr, in dieser Zeit sind auch telefonische Anfragen m\u00f6glich.<\/b><\/strong><\/p><p><strong><b>Belegte Tage sind im Kalender gekennzeichnet, \u00c4nderungen vorbehalten.<\/b><\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1705686 sc_height_huge animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"1705686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&hellip;<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"class_list":["post-166","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/pages\/166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/comments?post=166"}],"version-history":[{"count":0,"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/pages\/166\/revisions"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/en\/wp-json\/wp\/v2\/media?parent=166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}