{"id":7793,"date":"2025-02-28T09:34:39","date_gmt":"2025-02-28T08:34:39","guid":{"rendered":"https:\/\/kunstimaltenweingut.de\/?post_type=cpt_portfolio&#038;p=7793"},"modified":"2025-04-08T14:44:44","modified_gmt":"2025-04-08T12:44:44","slug":"corinth-walchensee","status":"publish","type":"cpt_portfolio","link":"https:\/\/kunstimaltenweingut.de\/de\/portfolio\/corinth-walchensee\/","title":{"rendered":"Lovis Corinth, Walchensee"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7793\" class=\"elementor elementor-7793\" data-elementor-post-type=\"cpt_portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ccc9538 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ccc9538\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79e274b0 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"79e274b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18bc74dd animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"18bc74dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lovis Corinth, Walchensee, 1924<br \/>\u00a9 public domain<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69eb1139 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69eb1139\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b02252a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"5b02252a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1f446e animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"f1f446e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e96bec9 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"e96bec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seit seinem ersten Aufenthalt zum 60. Geburtstag 1918 begeistert der oberbayerische Walchensee den in Berlin lebenden Maler Lovis Corinth. Die Faszination ist so gro\u00df, dass die Familie 1919 ein Grundst\u00fcck in Urfeld am Nordufer des Sees erwirbt und dort ein Sommerhaus errichten l\u00e4sst. Von seinem ans Schlafzimmer angrenzenden Balkon im ersten Stock genie\u00dft Corinth den weiten Blick \u00fcber die Bergwelt, und es kommt vor, dass er noch im Nachthemd zu Pinsel und Farbe greift, um in der k\u00fchlen Morgenluft seine expressiven Meisterwerke der Landschaftsmalerei zu schaffen.<\/p><p>Alle Aquarelle dieser herausragenden Sp\u00e4tphase sind <em>pleinair<\/em> entstanden, so auch \u201eWalchensee\u201c, gemalt w\u00e4hrend des letzten Sommers, den der Maler in Urfeld verbringen konnte. Zur Seite gezogen scheint ein Vorhang von B\u00e4umen links im Bild. Er gibt den Blick frei auf den sanft abfallenden Wiesenhang und kleine rotbraune H\u00e4user weit unten am Seeufer. Protagonisten des Bildes aber sind der Jochberg mit seinen bewaldeten H\u00e4ngen und zartgr\u00fcnen Almen und nat\u00fcrlich der Walchensee selbst, dessen dunkles Blau am Fu\u00df des Berges erstrahlt. Es bleibt der Fantasie des Betrachters \u00fcberlassen, ob er im Schatten auf dem Wasser ein Seeungheuer mit spitzen Z\u00e4hnen erkennen m\u00f6chte. Corinth selbst kannte auf jeden Fall die Sage vom riesigen Waller, dem die Einheimischen jedes Jahr einen geweihten Goldring in die Tiefen des Sees werfen, damit er Land und Leute nicht mit einem Schlag seiner ungeheuren Schwanzflosse \u00fcberschwemmt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e0fbad animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"27e0fbad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f29b884 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4f29b884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a6b9506 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2a6b9506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f407450 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"6f407450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_406605199\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Zur\u00fcck zur \u00dcbersicht <\/span><\/h4><div id=\"sc_button_203455687\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/de\/bildende-kunst-grafik\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Exponate Bildende Kunst Grafik<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e806005 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e806005\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7de232 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"d7de232\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b97921 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3b97921\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bildende Kunst, Grafik<\/p>\n","protected":false},"author":4,"featured_media":7798,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[128],"class_list":["post-7793","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-grafik"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/7793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/comments?post=7793"}],"version-history":[{"count":0,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/7793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media\/7798"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media?parent=7793"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio_group?post=7793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}