{"id":6622,"date":"2024-02-09T15:43:04","date_gmt":"2024-02-09T14:43:04","guid":{"rendered":"https:\/\/kunstimaltenweingut.de\/?post_type=cpt_portfolio&#038;p=6622"},"modified":"2024-02-09T15:43:06","modified_gmt":"2024-02-09T14:43:06","slug":"alabaster-gefaess","status":"publish","type":"cpt_portfolio","link":"https:\/\/kunstimaltenweingut.de\/de\/portfolio\/alabaster-gefaess\/","title":{"rendered":"Alabaster-Gef\u00e4\u00df"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6622\" class=\"elementor elementor-6622\" data-elementor-post-type=\"cpt_portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-32c26b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"32c26b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7361677c sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"7361677c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72926ec1 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"72926ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Von ebenm\u00e4\u00dfiger Sch\u00f6nheit ist dieses Gef\u00e4\u00df, das von der Handwerkskunst der fr\u00fchen dynastischen Periode zeugt. Den kugelf\u00f6rmigen Korpus mit flachem Boden ziert ein eingeritztes Gittermuster, das von vier kleinen \u00d6sen unterbrochen wird. Ein breiter Rand s\u00e4umt das Gef\u00e4\u00df rund um die \u00d6ffnung.\u00a0<\/p><p>Alabaster-Gestein war in \u00c4gypten ein beliebtes Material zur Herstellung von Gef\u00e4\u00dfen. Kleinere Alabastra fanden als Salbfl\u00e4schchen oder zur Aufbewahrung von Kosmetik und Parf\u00fcm Verwendung. Gr\u00f6\u00dfere wurden h\u00e4ufig in Gr\u00e4bern entdeckt, wo sie z.B. den Schmuck des Verstorbenen bargen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b9b693f animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"1b9b693f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33cd2706 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"33cd2706\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mehrere Deutungsm\u00f6glichkeiten hat die Bezeichnung Alabaster. Sie k\u00f6nnte sich von der ober\u00e4gyptischen Stadt <em>Alabastron Polis<\/em> herleiten, in deren N\u00e4he die Steinbr\u00fcche von Hatnub lagen. Eine andere Theorie \u00fcbersetzt den Begriff mit \u201eStein der G\u00f6ttin Bastet\u201c. Die katzenk\u00f6pfige G\u00f6ttin der Liebe und Fruchtbarkeit soll dem Mythos zufolge Schminkgef\u00e4\u00dfe aus dem weichen und warmen Material besessen haben. Eine dritte Herleitung bietet das griechische <em>alaba<\/em>, \u201eohne Henkel\u201c. Tats\u00e4chlich besa\u00dfen die kleinen Kosmetikfl\u00e4schchen, die von \u00c4gypten aus im gesamten \u00f6stlichen Mittelmeerraum gehandelt wurden, keine Henkel, sondern wurden mit Hilfe von \u00d6sen aufgeh\u00e4ngt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-272e2273 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"272e2273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-418a5789 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"418a5789\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65019cd7 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"65019cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_516802401\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Zur\u00fcck zur \u00dcbersicht <\/span><\/h4><div id=\"sc_button_1984671119\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/de\/aegyptische-kunst\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Alle Exponate \u00c4gyptische Kunst<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c4gyptische Kunst<\/p>\n","protected":false},"author":4,"featured_media":6627,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[61],"class_list":["post-6622","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-aegypten"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/6622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/comments?post=6622"}],"version-history":[{"count":0,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/6622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media\/6627"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media?parent=6622"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio_group?post=6622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}