{"id":5695,"date":"2023-08-14T08:34:48","date_gmt":"2023-08-14T06:34:48","guid":{"rendered":"https:\/\/kunstimaltenweingut.de\/?post_type=cpt_portfolio&#038;p=5695"},"modified":"2026-04-12T11:39:18","modified_gmt":"2026-04-12T09:39:18","slug":"pierre-schumann-marmorstier","status":"publish","type":"cpt_portfolio","link":"https:\/\/kunstimaltenweingut.de\/de\/portfolio\/pierre-schumann-marmorstier\/","title":{"rendered":"Pierre Schumann, Marmorstier"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5695\" class=\"elementor elementor-5695\" data-elementor-post-type=\"cpt_portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cb845d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cb845d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49ccd6bd sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"49ccd6bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e87979b animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"1e87979b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pierre Schumann, Marmorstier<br \/>\u00a9 Pierre Schumann Erbengemeinschaft, 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d0a85f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d0a85f8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a7f07a sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"6a7f07a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4da124 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a4da124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38cd01af animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"38cd01af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der schleswig-holsteinische Bildhauer Pierre Schumann war ein Meister der Reduktion. Mit Linien, die einfacher und klarer kaum sein k\u00f6nnten, gelang es ihm auch hier, den Urtypus eines vor Kraft strotzenden Stiers aus einem schwarzen Steinblock zu mei\u00dfeln. Archaische Formsprache vereint sich mit der Eleganz des auf Hochglanz polierten Materials. Dieses mutet zwar wie Marmor \u2013 Schumanns bevorzugtes Material \u2013 an, tats\u00e4chlich handelt es sich aber um einen h\u00f6chst exklusiven Kalkstein: Nero Portoro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e99005a animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4e99005a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b8e4f8 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"48b8e4f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Name des ligurischen Natursteins beinhaltet \u201eNero\u201c f\u00fcr seine schwarze Farbe, \u201ePorto\u201c f\u00fcr die Ortschaft Porto Venere nahe der Steinbr\u00fcche und \u201eOro\u201c f\u00fcr die goldfarbenen Adern, die das Gestein durchziehen. Diese Maserung tr\u00e4gt zum dynamischen und lebendigen Gesamteindruck der kleinen Skulptur bei.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd4eba7 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4cd4eba7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-166d1903 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"166d1903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206a9115 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"206a9115\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_794130046\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Zur\u00fcck zur \u00dcbersicht <\/span><\/h4><div id=\"sc_button_893968786\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/bildende-kunst-skulptur\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Exponate Bildende Kunst Skulptur<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bildende Kunst, Skulptur<\/p>\n","protected":false},"author":4,"featured_media":5701,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[130],"class_list":["post-5695","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-skulptur"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/5695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/comments?post=5695"}],"version-history":[{"count":1,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/5695\/revisions"}],"predecessor-version":[{"id":8979,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/5695\/revisions\/8979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media\/5701"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media?parent=5695"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio_group?post=5695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}