{"id":5037,"date":"2023-04-17T08:55:36","date_gmt":"2023-04-17T06:55:36","guid":{"rendered":"https:\/\/kunstimaltenweingut.de\/?post_type=cpt_portfolio&#038;p=5037"},"modified":"2025-02-28T10:14:48","modified_gmt":"2025-02-28T09:14:48","slug":"ben-vautier-regarde-toi-voleur-de-cultures-1990","status":"publish","type":"cpt_portfolio","link":"https:\/\/kunstimaltenweingut.de\/de\/portfolio\/ben-vautier-regarde-toi-voleur-de-cultures-1990\/","title":{"rendered":"Ben Vautier, regarde toi! voleur de cultures, 1990"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5037\" class=\"elementor elementor-5037\" data-elementor-post-type=\"cpt_portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4512275 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4512275\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21b4a63b sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"21b4a63b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-165f2389 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"165f2389\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ben Vautier, regarde toi! voleur de cultures, 1990<br \/>\u00a9 VG Bild Kunst, Bonn 2023<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7890699e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7890699e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b8ef0a5 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"5b8ef0a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d16457 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6d16457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-257f5f08 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"257f5f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Was f\u00fcr eine Provokation! \u201eregarde toi! voleur de cultures\u201c (\u201eSchau dich an! Kulturdieb\u201c), hei\u00dft es fein s\u00e4uberlich in den unverwechselbaren wei\u00dfen Schreibschriftlettern des schweizerisch-franz\u00f6sischen K\u00fcnstlers Ben Vautier. Die Worte stehen auf der dunklen Holzplatte, auf der in wei\u00df skizziertem Rahmen eine ebenm\u00e4\u00dfige afrikanische Maske angebracht ist, sowie auf dem dreiteiligen Rasierspiegel darunter. In diesem kann der Kulturdieb, voleur de cultures, sich selbst erkennen.<\/p><p>Ben Vautier, der aus einer ber\u00fchmten K\u00fcnstlerfamilie stammt, ist ein Pionier der Fluxus-Bewegung der 1960er-Jahre in Nizza. Diese hatte es sich zur Aufgabe gemacht, den Kunstbegriff im Erbe von Dada kontinuierlich zu erweitern. So f\u00fchrte Vautier beispielsweise mehrere Jahre lang einen Plattenladen, der zum Treffpunkt und Ausstellungsort f\u00fcr K\u00fcnstler wurde, die \u201eNeues\u201c machen wollten und dessen Fassade schlie\u00dflich sogar als Kunstobjekt im Centre Pompidou ausgestellt wurde. Kunst und Leben sollten eine Einheit bilden, Grenzen verschwimmen.<\/p><p>Auch in \u201eregarde toi! voleur de cultures\u201c verschwimmen Grenzen. Rein formal kombiniert Vautier hier Textbild und Objets trouv\u00e9s. Dar\u00fcber hinaus wird der Betrachter durch den Spiegel selbst zum Bestandteil des Kunstwerks. Afrika und Europa treten in Verbindung. Und die provokanten Worte des K\u00fcnstlers lassen diesen selbst anwesend erscheinen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-619a29c5 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"619a29c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b04611f animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"b04611f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3877e661 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3877e661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce23ce0 animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"ce23ce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_362229424\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Zur\u00fcck zur \u00dcbersicht <\/span><\/h4><div id=\"sc_button_2048264176\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/bildende-kunst-mixed-media\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Exponate Bildende Kunst Mixed Media<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bildende Kunst, Mixed Media<\/p>\n","protected":false},"author":4,"featured_media":5042,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[129],"class_list":["post-5037","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-mixed-media"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/5037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/comments?post=5037"}],"version-history":[{"count":0,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/5037\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media\/5042"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media?parent=5037"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio_group?post=5037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}