{"id":3294,"date":"2022-09-28T14:28:34","date_gmt":"2022-09-28T14:28:34","guid":{"rendered":"https:\/\/kunstimaltenweingut.de\/?post_type=cpt_portfolio&#038;p=3294"},"modified":"2026-06-19T17:58:50","modified_gmt":"2026-06-19T15:58:50","slug":"karlheinz-oswald-stelena-1-und-stelena-2","status":"publish","type":"cpt_portfolio","link":"https:\/\/kunstimaltenweingut.de\/de\/portfolio\/karlheinz-oswald-stelena-1-und-stelena-2\/","title":{"rendered":"Karlheinz Oswald, Stelena 1 und Stelena 2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3294\" class=\"elementor elementor-3294\" data-elementor-post-type=\"cpt_portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-287614c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"287614c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bb6de9 sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"9bb6de9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20dc1ed animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"20dc1ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Karlheinz Oswald, Stelena 1 und Stelena 2, 2021<br \/>\u00a9 Karlheinz Oswald, 2022<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-203d69e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"203d69e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f40754e sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left\" data-id=\"7f40754e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e48cef animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6e48cef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d85c6 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"4d85c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tanz. Lebensfreude. Exotik. All dies vereinen die beiden Statuen, die die Aufmerksamkeit des Besuchers im Innenhof des ehemaligen Weinguts auf sich lenken. Als erste Kunstwerke zogen sie 2021 in den neu gegr\u00fcndeten Museumskomplex Obentraut3 ein und stehen programmatisch f\u00fcr die Vision des Stifterpaars Dirk und Heidrun Gem\u00fcnden: Die Erschaffung eines Begegnungsortes, an dem Sch\u00f6nheit und Dynamik, Lebendigkeit und Weltoffenheit Hand in Hand gehen.<\/p><p>Stelena 1 und Stelena 2 sind Werke des in Worms geborenen und international bekannten K\u00fcnstlers Karlheinz Oswald. Dieser besch\u00e4ftigt sich seit seinem Studium an der Universit\u00e4t Mainz intensiv mit den Thematiken Tanz und Bewegung. Meisterhaft gelingt es ihm, seine aus Eisen gegossenen Plastiken geradezu schwerelos Richtung Himmel streben zu lassen. Umrisse l\u00f6sen sich flatternd auf, selbstvergessen erscheinen die sch\u00f6nen, orientalisch anmutenden Gesichter der T\u00e4nzerinnen, geschm\u00fcckt mit gro\u00dfen runden Ohrringen.<\/p><p>Obgleich auf eigenen Sockeln platziert, korrespondieren ihre expressiven Bewegungen miteinander und verschmelzen zu einer dynamischen Einheit. Vertr\u00e4umt und zugleich unglaublich pr\u00e4sent scheinen sich die beiden Frauen dem Rhythmus einer unh\u00f6rbaren Musik hinzugeben. Die Schwere des Metalls und die Leichtigkeit der Bewegung, die fein herausgearbeiteten Gesichtsz\u00fcge und die schnell skizzierten Gew\u00e4nder, die \u00fcberraschende halbrunde Form der hohen, schmalen Sockel \u2013 das Werk Karlheinz Oswalds ist voll \u00e4sthetischer Spannung und Raffinesse.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18613816 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"18613816\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fcf3f3 animation_type_block sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"2fcf3f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mehr lesen:<\/strong> <a href=\"https:\/\/kunstimaltenweingut.de\/karlheinz-oswald-menschenbilder\/\">Karlheinz Oswald &#8211; Menschenbilder<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ede142 animation_type_block sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"7ede142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19c53fe animation_type_block sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"19c53fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"trx_sc_title_364932123\"\n\t\tclass=\"sc_title color_style_dark sc_title_decoration extra_vision\"><h4 class=\"sc_item_title sc_title_title sc_item_title_style_decoration sc_item_title_tag\"><span class=\"sc_item_title_text\">Zur\u00fcck zur \u00dcbersicht <\/span><\/h4><div id=\"sc_button_56899993\"\tclass=\"sc_item_button sc_button_wrap sc_item_button sc_item_button_simple sc_title_button\"><a href=\"https:\/\/kunstimaltenweingut.de\/bildende-kunst-skulptur\/\" class=\"sc_button sc_button_simple sc_button_size_normal sc_button_icon_left\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">Exponate Bildende Kunst Skulptur<\/span><\/span><!-- \/.sc_button_text --><\/a><!-- \/.sc_button --><\/div><!-- \/.sc_item_button --><\/div><!-- \/.sc_title -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bildende Kunst, Skulptur<\/p>\n","protected":false},"author":4,"featured_media":3206,"comment_status":"closed","ping_status":"closed","template":"","cpt_portfolio_group":[130],"class_list":["post-3294","cpt_portfolio","type-cpt_portfolio","status-publish","has-post-thumbnail","hentry","cpt_portfolio_group-skulptur"],"jetpack_sharing_enabled":true,"ticketed":false,"_links":{"self":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/3294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio"}],"about":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/types\/cpt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/comments?post=3294"}],"version-history":[{"count":6,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/3294\/revisions"}],"predecessor-version":[{"id":9155,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio\/3294\/revisions\/9155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media\/3206"}],"wp:attachment":[{"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/media?parent=3294"}],"wp:term":[{"taxonomy":"cpt_portfolio_group","embeddable":true,"href":"https:\/\/kunstimaltenweingut.de\/de\/wp-json\/wp\/v2\/cpt_portfolio_group?post=3294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}